{"id":7335,"date":"2023-10-12T15:15:00","date_gmt":"2023-10-12T20:15:00","guid":{"rendered":"https:\/\/www.sedarauca.edu.co\/?p=7335"},"modified":"2023-10-19T15:32:02","modified_gmt":"2023-10-19T20:32:02","slug":"en-arauca-se-realizo-el-ii-encuentro-nacional-de-la-red-de-innovacion-e-intercambio-de-experiencias-pedagogicas","status":"publish","type":"post","link":"https:\/\/www.sedarauca.edu.co\/index.php\/2023\/10\/12\/en-arauca-se-realizo-el-ii-encuentro-nacional-de-la-red-de-innovacion-e-intercambio-de-experiencias-pedagogicas\/","title":{"rendered":"<strong>En Arauca se realiz\u00f3 el II Encuentro Nacional de la Red de Innovaci\u00f3n e Intercambio de Experiencias Pedag\u00f3gicas<\/strong>"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_margin=\u00bb-40px||||false|false\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><strong>Arauca, 12 de octubre de 2023\u00a0&#8211;<\/strong> Durante los pasados d\u00edas 9, 10 y 11 de octubre, la ciudad capital de Arauca fue el escenario del II Encuentro Nacional de la Red de Innovaci\u00f3n e Intercambio de Experiencias Pedag\u00f3gicas (RIIEP). Este evento, que congreg\u00f3 a educadores de todo el pa\u00eds, brind\u00f3 una plataforma para compartir las experiencias pedag\u00f3gicas de docentes colombianos que se destacan por su labor investigativa e innovadora en sus contextos escolares.<\/p>\n<p style=\"text-align: justify;\">La RIIEP, una red de maestras y maestros que promueve la colaboraci\u00f3n y el intercambio de conocimientos en Latinoam\u00e9rica, actualmente cuenta con la participaci\u00f3n de pa\u00edses como Colombia, Rep\u00fablica Dominicana, Honduras, Per\u00fa, Cuba y M\u00e9xico. Adem\u00e1s, se encuentra en proceso de articulaci\u00f3n con Argentina y Uruguay, lo que promete un crecimiento continuo y una mayor diversidad de perspectivas educativas.<\/p>\n<p style=\"text-align: justify;\">El departamento de Arauca, con su compromiso y dedicaci\u00f3n, se ha convertido en un referente fundamental en la labor de la RIIEP. Durante el evento, se destacaron las contribuciones y proyectos de docentes tanto en formaci\u00f3n como en ejercicio, demostrando el impacto positivo de la red en el \u00e1mbito educativo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb column_structure=\u00bb1_3,1_3,1_3&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_3&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.sedarauca.edu.co\/wp-content\/uploads\/2023\/10\/391756039_815469440584282_6507426534560239668_n.jpg\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bb391756039_815469440584282_6507426534560239668_n\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_3&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.sedarauca.edu.co\/wp-content\/uploads\/2023\/10\/Imagen3-a.jpg\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bbImagen3-a\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb1_3&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/www.sedarauca.edu.co\/wp-content\/uploads\/2023\/10\/359de839-1cca-4195-b4bf-fdf49593a621.jpg\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bb359de839-1cca-4195-b4bf-fdf49593a621&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\">El profesor Alonso Prada asumi\u00f3 un papel destacado en la organizaci\u00f3n de este encuentro, contando con el valioso respaldo de la Secretar\u00eda de Educaci\u00f3n Departamental de Arauca y la Asociaci\u00f3n de Educadores del Arauca. Su liderazgo fue fundamental para el \u00e9xito del evento y para fomentar la colaboraci\u00f3n entre los educadores presentes.<\/p>\n<p style=\"text-align: justify;\">Este II Encuentro Nacional de la RIIEP se erige como un espacio crucial para el fortalecimiento de la educaci\u00f3n en Colombia y la regi\u00f3n latinoamericana, promoviendo la innovaci\u00f3n y el intercambio de experiencias pedag\u00f3gicas que enriquecen el proceso de ense\u00f1anza-aprendizaje.<\/p>\n<p style=\"text-align: justify;\">La RIIEP sigue avanzando en su misi\u00f3n de mejorar la educaci\u00f3n en Am\u00e9rica Latina, y eventos como este demuestran el compromiso de los docentes por elevar la calidad de la ense\u00f1anza y el aprendizaje en la regi\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arauca, 12 de octubre de 2023\u00a0&#8211; Durante los pasados d\u00edas 9, 10 y 11 de octubre, la ciudad capital de Arauca fue el escenario del II Encuentro Nacional de la Red de Innovaci\u00f3n e Intercambio de Experiencias Pedag\u00f3gicas (RIIEP). Este evento, que congreg\u00f3 a educadores de todo el pa\u00eds, brind\u00f3 una plataforma para compartir las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-7335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/7335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=7335"}],"version-history":[{"count":2,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/7335\/revisions"}],"predecessor-version":[{"id":7343,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/7335\/revisions\/7343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media\/7337"}],"wp:attachment":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=7335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=7335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=7335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}