{"id":14974,"date":"2026-04-30T09:29:00","date_gmt":"2026-04-30T14:29:00","guid":{"rendered":"https:\/\/www.sedarauca.edu.co\/?p=14974"},"modified":"2026-05-06T09:36:37","modified_gmt":"2026-05-06T14:36:37","slug":"esto-fue-lo-mejor-de-la-educacion-en-abril","status":"publish","type":"post","link":"https:\/\/www.sedarauca.edu.co\/index.php\/2026\/04\/30\/esto-fue-lo-mejor-de-la-educacion-en-abril\/","title":{"rendered":"Esto fue lo mejor de la educaci\u00f3n en abril"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p style=\"text-align: justify;\"><strong>Arauca, 30 de abril de 2026.\u00a0<\/strong>El mes de abril reflej\u00f3 avances importantes en distintos frentes del sector educativo, consolidando acciones que fortalecen la calidad, el acceso y las oportunidades para nuestros estudiantes en el departamento de Arauca, aqu\u00ed te contamos la gesti\u00f3n de la secretar\u00eda de Educaci\u00f3n Departamental:<\/p>\n<p style=\"text-align: justify;\">En el marco del Mes de la Ni\u00f1ez, promovimos el juego como una herramienta pedag\u00f3gica clave en nuestras instituciones educativas. A trav\u00e9s de espacios participativos, ni\u00f1os y ni\u00f1as compartieron sus ideas para construir entornos de aprendizaje m\u00e1s creativos, incluyentes y significativos, reafirmando su papel como protagonistas del proceso educativo.<\/p>\n<p style=\"text-align: justify;\">En materia de gesti\u00f3n institucional, recibimos la visita del Ministerio de Educaci\u00f3n Nacional en el marco de la Asistencia T\u00e9cnica Integral, con resultados altamente positivos. Se destacaron avances en planta docente, educaci\u00f3n inicial, gesti\u00f3n de recursos y estrategias de acceso y permanencia, consolidando una hoja de ruta clara para seguir fortaleciendo el servicio educativo en el departamento.<\/p>\n<p style=\"text-align: justify;\">En cuanto a acceso y permanencia, continuamos con jornadas de b\u00fasqueda activa en diferentes municipios, llegando a los hogares para vincular a ni\u00f1os, ni\u00f1as y j\u00f3venes que a\u00fan no est\u00e1n matriculados, reafirmando nuestro compromiso de que todos est\u00e9n en el sistema educativo.<\/p>\n<p style=\"text-align: justify;\">Seguimos fortaleciendo las capacidades de nuestros docentes, especialmente en educaci\u00f3n inicial, a trav\u00e9s de espacios como el Taller de Armonizaci\u00f3n Curricular, orientado a mejorar las pr\u00e1cticas pedag\u00f3gicas y garantizar el desarrollo integral de los ni\u00f1os y ni\u00f1as desde sus primeros a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">El Programa de Alimentaci\u00f3n Escolar (PAE) tambi\u00e9n registr\u00f3 avances importantes. Realizamos con \u00e9xito la Primera Mesa P\u00fablica 2026, fortaleciendo la transparencia, la participaci\u00f3n ciudadana. Igualmente realizamos el Comit\u00e9 Territorial de Planeaci\u00f3n y Seguimiento (CTPS) y socializamos el PAE para comunidades NARP (Negras, Afrocolombianas, Raizales y Palenqueras), dando cumplimiento a la Resoluci\u00f3n 051 de 2025.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_gallery _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb gallery_ids=\u00bb14979,14980,14981,14982,14983,14984,14985,14986,14987,14988,14989&#8243; gallery_orderby=\u00bbrand\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_margin=\u00bb-50px||||false|false\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p style=\"text-align: justify;\">En escenarios nacionales e internacionales, seguimos posicionando la educaci\u00f3n de Arauca. Nuestro secretario de Educaci\u00f3n particip\u00f3 en un encuentro internacional de l\u00edderes educativos en Argentina, fortaleciendo el intercambio de experiencias, y acompa\u00f1\u00f3 la Mesa Nacional de Salud del Magisterio, un espacio clave para mejorar las condiciones de atenci\u00f3n de nuestros docentes.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El acceso a la educaci\u00f3n superior fue uno de los ejes m\u00e1s relevantes del mes, avanzamos en articulaci\u00f3n con la Universidad Nacional de Colombia, proyectando el crecimiento de la sede Orinoqu\u00eda con nuevos programas como Ingenier\u00eda de Alimentos, Dise\u00f1o Integrado, Arquitectura, Ingenier\u00eda Ambiental e Ingenier\u00eda Agroindustrial, as\u00ed como el aumento de cobertura y nuevas cohortes.<\/p>\n<p style=\"text-align: justify;\">De igual manera, desde Arauquita se lider\u00f3 una mesa de trabajo con la Universidad Nacional Abierta y a Distancia (UNAD), en la que se socializ\u00f3 la hoja de ruta para la culminaci\u00f3n de las obras del Centro Comunitario de Atenci\u00f3n Virtual, una iniciativa que ampliar\u00e1 el acceso a la educaci\u00f3n superior en el territorio.<\/p>\n<p style=\"text-align: justify;\">En este mismo prop\u00f3sito, promovimos activamente la inscripci\u00f3n al proceso de las pruebas SABER 11 del ICFES, invitando a directivos docentes, padres de familia y estudiantes de grado 11 a participar, entendiendo que este paso es fundamental para facilitar el acceso a la educaci\u00f3n superior.<\/p>\n<p style=\"text-align: justify;\">Finalmente, destacamos un logro en equidad educativa: por primera vez, los estudiantes de los siete municipios del departamento podr\u00e1n presentar las Pruebas Saber 11 en su propio territorio, garantizando mejores condiciones y reduciendo barreras para el acceso a la educaci\u00f3n superior.<\/p>\n<p style=\"text-align: justify;\">Desde la Secretar\u00eda de Educaci\u00f3n Departamental seguimos trabajando de manera articulada para que la educaci\u00f3n contin\u00fae siendo el motor de desarrollo y transformaci\u00f3n social en Arauca.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Arauca, 30 de abril de 2026.\u00a0El mes de abril reflej\u00f3 avances importantes en distintos frentes del sector educativo, consolidando acciones que fortalecen la calidad, el acceso y las oportunidades para nuestros estudiantes en el departamento de Arauca, aqu\u00ed te contamos la gesti\u00f3n de la secretar\u00eda de Educaci\u00f3n Departamental: En el marco del Mes de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[21,6],"tags":[],"class_list":["post-14974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=14974"}],"version-history":[{"count":4,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14974\/revisions"}],"predecessor-version":[{"id":14991,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14974\/revisions\/14991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media\/14975"}],"wp:attachment":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=14974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=14974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=14974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}