{"id":14908,"date":"2026-04-29T11:52:00","date_gmt":"2026-04-29T16:52:00","guid":{"rendered":"https:\/\/www.sedarauca.edu.co\/?p=14908"},"modified":"2026-05-05T15:22:34","modified_gmt":"2026-05-05T20:22:34","slug":"gobernacion-de-arauca-avanza-en-la-planeacion-del-pae-con-enfoque-diferencial-para-comunidades-narp","status":"publish","type":"post","link":"https:\/\/www.sedarauca.edu.co\/index.php\/2026\/04\/29\/gobernacion-de-arauca-avanza-en-la-planeacion-del-pae-con-enfoque-diferencial-para-comunidades-narp\/","title":{"rendered":"Gobernaci\u00f3n de Arauca avanza en la planeaci\u00f3n del PAE con enfoque diferencial para comunidades NARP"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb custom_margin=\u00bb-30px||||false|false\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><strong>Arauca, 29 de abril de 2026.\u00a0<\/strong>La Secretar\u00eda de Educaci\u00f3n Departamental llev\u00f3 a cabo el Comit\u00e9 Territorial de Planeaci\u00f3n y Seguimiento (CTPS), un espacio estrat\u00e9gico para el fortalecimiento del Programa de Alimentaci\u00f3n Escolar (PAE) en el departamento de Arauca.<\/p>\n<p style=\"text-align: justify;\">Durante esta sesi\u00f3n extraordinaria, se realiz\u00f3 la socializaci\u00f3n del modelo del PAE para comunidades Negras, Afrocolombianas, Raizales y Palenqueras (NARP), en el marco de la Resoluci\u00f3n 051 de 2025. Este ejercicio marca el inicio de un proceso que contempla las etapas de planeaci\u00f3n, alistamiento y estructuraci\u00f3n, con miras a su futura implementaci\u00f3n en el territorio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb14913,14914,14915,14916&#8243; gallery_orderby=\u00bbrand\u00bb dbdb_version=\u00bb4.2.9&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">El prop\u00f3sito de este modelo es que, una vez surtidas las fases correspondientes, el programa pueda ser operado por las mismas comunidades, garantizando un enfoque diferencial que reconozca sus pr\u00e1cticas culturales, sus sistemas alimentarios propios y su autonom\u00eda organizativa.<\/p>\n<p style=\"text-align: justify;\">Con este avance, el departamento de Arauca contin\u00faa consolid\u00e1ndose como referente en la atenci\u00f3n diferencial dentro del PAE, sumando esta l\u00ednea a las modalidades ya existentes: Mayoritaria, Rural Dispersa e Ind\u00edgena.<\/p>\n<p style=\"text-align: justify;\">Asimismo, durante el comit\u00e9 se reiter\u00f3 la articulaci\u00f3n del departamento con los nuevos lineamientos establecidos en la Resoluci\u00f3n 003 de 2026 de la Unidad Administrativa Especial de Alimentaci\u00f3n Escolar (UAPA), orientados a fortalecer la calidad y eficiencia en la prestaci\u00f3n del servicio.<\/p>\n<p style=\"text-align: justify;\">La Gobernaci\u00f3n de Arauca reafirma su compromiso con una educaci\u00f3n inclusiva y pertinente, avanzando en procesos de planificaci\u00f3n que garantizan, a futuro, una alimentaci\u00f3n escolar con enfoque diferencial, construida desde y para las comunidades del territorio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arauca, 29 de abril de 2026.\u00a0La Secretar\u00eda de Educaci\u00f3n Departamental llev\u00f3 a cabo el Comit\u00e9 Territorial de Planeaci\u00f3n y Seguimiento (CTPS), un espacio estrat\u00e9gico para el fortalecimiento del Programa de Alimentaci\u00f3n Escolar (PAE) en el departamento de Arauca. Durante esta sesi\u00f3n extraordinaria, se realiz\u00f3 la socializaci\u00f3n del modelo del PAE para comunidades Negras, Afrocolombianas, Raizales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[21,6,17,1],"tags":[],"class_list":["post-14908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletin","category-noticias","category-pae","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=14908"}],"version-history":[{"count":4,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14908\/revisions"}],"predecessor-version":[{"id":14928,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/14908\/revisions\/14928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media\/14909"}],"wp:attachment":[{"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=14908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=14908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sedarauca.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=14908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}